{"id":356,"date":"2019-04-17T21:13:26","date_gmt":"2019-04-17T21:13:26","guid":{"rendered":"http:\/\/demos.upperthemes.com\/larch\/elements\/?page_id=356"},"modified":"2019-04-17T21:13:26","modified_gmt":"2019-04-17T21:13:26","slug":"icons-info-box","status":"publish","type":"page","link":"http:\/\/demos.upperthemes.com\/koral\/headerstyle3\/elements\/icons-info-box\/","title":{"rendered":"Icons &amp; Info Box"},"content":{"rendered":"<p>\t\t\t\t[vc_row css=&#8221;.vc_custom_1531501256718{padding-top: 80px !important;padding-bottom: 120px !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;INFO BOX | TOOLTIP DESCRIPTION&#8221; font_container=&#8221;tag:h2|font_size:18px|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_empty_space height=&#8221;80px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-4737\" class=\"aio-icon-box tooltip-icon\" style=\"\"  ><div class=\"aio-icon-tooltip\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon circle \"  style=\"color:#ffffff;background:#101010;font-size:30px;display:inline-block;\">\n\t<i class=\"linearicons-spades\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-4737 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Circle Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-4737 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"color:#f4f4f4;\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-3542\" class=\"aio-icon-box tooltip-icon\" style=\"\"  ><div class=\"aio-icon-tooltip\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon advanced \"  style=\"color:#ffffff;background:#101010;border-style:;border-color:#333333;border-width:1px;width:55px;height:55px;line-height:55px;border-radius:500px;font-size:30px;display:inline-block;\">\n\t<i class=\"linearicons-shield-check\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-3542 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Circle Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-3542 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"color:#f7f7f7;\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-3603\" class=\"aio-icon-box tooltip-icon\" style=\"\"  ><div class=\"aio-icon-tooltip\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon circle \"  style=\"color:#ffffff;background:#101010;font-size:30px;display:inline-block;\">\n\t<i class=\"linearicons-paint-roller\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-3603 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Circle Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-3603 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-1941\" class=\"aio-icon-box tooltip-icon\" style=\"\"  ><div class=\"aio-icon-tooltip\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon circle \"  style=\"color:#ffffff;background:#101010;font-size:30px;display:inline-block;\">\n\t<i class=\"linearicons-server\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-1941 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Circle Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-1941 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1462203830473{padding-top: 40px !important;padding-bottom: 40px !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;INFO BOX | CENTERED ICON&#8221; font_container=&#8221;tag:h2|font_size:18px|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_empty_space height=&#8221;80px&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1483479862325{padding-bottom: 50px !important;}&#8221;][vc_column width=&#8221;1\/4&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-5595\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#101010;font-size:40px;display:inline-block;\">\n\t<i class=\"Defaults-wrench\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-5595 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Simple Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-5595 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][vc_column width=&#8221;1\/4&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-7098\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#101010;font-size:40px;display:inline-block;\">\n\t<i class=\"Defaults-headphones\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-7098 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Simple Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-7098 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][vc_column width=&#8221;1\/4&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-6536\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon circle \"  style=\"color:#ffffff;background:#101010;font-size:23px;display:inline-block;\">\n\t<i class=\"Defaults-star\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-6536 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Circle Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-6536 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][vc_column width=&#8221;1\/4&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-2965\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon square \"  style=\"color:#ffffff;background:#101010;font-size:23px;display:inline-block;\">\n\t<i class=\"Defaults-lock\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-2965 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Square Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-2965 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1462207384660{padding-bottom: 50px !important;}&#8221;][vc_column width=&#8221;1\/4&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-5065\" class=\"aio-icon-box square_box-icon\" style=\"border-color:#ededed;border-style:double;border-width:2px;\" data-min-height='200px' ><div class=\"aio-icon-square_box\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon circle \"  style=\"color:#ffffff;background:#101010;font-size:30px;display:inline-block;\">\n\t<i class=\"Defaults-leaf\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-5065 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Circle Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-5065 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][vc_column width=&#8221;1\/4&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-3317\" class=\"aio-icon-box square_box-icon\" style=\"border-color:rgba(52,132,193,0.19);border-style:dashed;border-width:2px;\" data-min-height='200px' ><div class=\"aio-icon-square_box\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon advanced \"  style=\"color:#101010;background:#ededed;border-style:solid;border-color:#ededed;border-width:2px;width:55px;height:55px;line-height:55px;border-radius:500px;font-size:30px;display:inline-block;\">\n\t<i class=\"Defaults-download\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-3317 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Circle Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-3317 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][vc_column width=&#8221;1\/4&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-5085\" class=\"aio-icon-box square_box-icon\" style=\"border-color:#101010;border-style:solid;border-width:2px;background-color:#101010;\" data-min-height='200px' ><div class=\"aio-icon-square_box\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon advanced \"  style=\"color:#101010;background:#ffffff;border-style:;border-color:#333333;border-width:1px;width:55px;height:55px;line-height:55px;border-radius:500px;font-size:30px;display:inline-block;\">\n\t<i class=\"Defaults-bell-o\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-5085 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"color:#ffffff;\">Circle Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-5085 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"color:#f2f2f2;\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][vc_column width=&#8221;1\/4&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-1830\" class=\"aio-icon-box square_box-icon\" style=\"border-style:solid;background-color:#f5f5f5;\" data-min-height='200px' ><div class=\"aio-icon-square_box\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon square \"  style=\"color:#ffffff;background:#101010;font-size:30px;display:inline-block;\">\n\t<i class=\"linearicons-reading\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-1830 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Square Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-1830 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"color:#848484;\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][\/vc_row][vc_row bg_type=&#8221;bg_color&#8221; bg_override=&#8221;ex-full&#8221; css=&#8221;.vc_custom_1483481746588{padding-top: 120px !important;padding-bottom: 120px !important;}&#8221; bg_color_value=&#8221;#f7f7f7&#8243;][vc_column][vc_custom_heading text=&#8221;INFO BOX | LEFT ICON&#8221; font_container=&#8221;tag:h2|font_size:18px|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_empty_space height=&#8221;80px&#8221;][vc_row_inner css=&#8221;.vc_custom_1463690505589{margin-bottom: 40px !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-8926\" class=\"aio-icon-box left-icon\" style=\"\"  ><div class=\"aio-icon-left\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#101010;font-size:40px;display:inline-block;\">\n\t<i class=\"linearicons-factory\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-ibd-block\"><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-8926 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Simple Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-8926 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-ibd-block --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-3987\" class=\"aio-icon-box left-icon\" style=\"\"  ><div class=\"aio-icon-left\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#101010;font-size:40px;display:inline-block;\">\n\t<i class=\"linearicons-hat\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-ibd-block\"><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-3987 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Simple Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-3987 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-ibd-block --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-4763\" class=\"aio-icon-box left-icon\" style=\"\"  ><div class=\"aio-icon-left\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon circle \"  style=\"color:#ffffff;background:#101010;font-size:23px;display:inline-block;\">\n\t<i class=\"linearicons-cable2\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-ibd-block\"><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-4763 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Circle Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-4763 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-ibd-block --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-2159\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#84566e;font-size:40px;display:inline-block;\">\n\t<i class=\"linearicons-album\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-2159 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Simple Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-2159 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-6835\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#101010;font-size:40px;display:inline-block;\">\n\t<i class=\"linearicons-register\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-6835 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Simple Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-6835 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-2425\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon circle \"  style=\"color:#ffffff;background:#101010;font-size:23px;display:inline-block;\">\n\t<i class=\"linearicons-laptop-phone\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-2425 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Circle Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-2425 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1462203830473{padding-top: 40px !important;padding-bottom: 40px !important;}&#8221;][vc_column][vc_empty_space height=&#8221;80px&#8221;][vc_custom_heading text=&#8221;INFO BOX | RIGHT ICON&#8221; font_container=&#8221;tag:h2|font_size:18px|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_empty_space height=&#8221;15px&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1462371330185{padding-top: 40px !important;padding-bottom: 50px !important;}&#8221;][vc_column width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-3790\" class=\"aio-icon-box right-icon\" style=\"\"  ><div class=\"aio-ibd-block\" ><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-3790 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Simple Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-3790 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-ibd-block --><div class=\"aio-icon-right\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#101010;font-size:40px;display:inline-block;\">\n\t<i class=\"linearicons-panorama\"><\/i>\n<\/div><\/div><\/div><\/div><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][vc_column width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-3625\" class=\"aio-icon-box right-icon\" style=\"\"  ><div class=\"aio-ibd-block\" ><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-3625 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Simple Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-3625 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-ibd-block --><div class=\"aio-icon-right\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#101010;font-size:40px;display:inline-block;\">\n\t<i class=\"linearicons-bench-press\"><\/i>\n<\/div><\/div><\/div><\/div><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][vc_column width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-1010\" class=\"aio-icon-box right-icon\" style=\"\"  ><div class=\"aio-ibd-block\" ><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-1010 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Circle Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-1010 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-ibd-block --><div class=\"aio-icon-right\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon square \"  style=\"color:#ffffff;background:#101010;font-size:23px;display:inline-block;\">\n\t<i class=\"linearicons-chef\"><\/i>\n<\/div><\/div><\/div><\/div><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1462371330185{padding-top: 40px !important;padding-bottom: 50px !important;}&#8221;][vc_column width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-8461\" class=\"aio-icon-box heading-right-icon\" style=\"\"  ><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-8461 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Simple Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-heading-right\" ><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#101010;font-size:40px;display:inline-block;\">\n\t<i class=\"linearicons-star-half\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-8461 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][vc_column width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-6774\" class=\"aio-icon-box heading-right-icon\" style=\"\"  ><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-6774 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Simple Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-heading-right\" ><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#101010;font-size:40px;display:inline-block;\">\n\t<i class=\"linearicons-bucket\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-6774 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][vc_column width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-3879\" class=\"aio-icon-box heading-right-icon\" style=\"\"  ><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-3879 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Circle Icon at top<\/h3><\/div> <!-- header --><div class=\"aio-icon-heading-right\" ><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon circle \"  style=\"color:#ffffff;background:#101010;font-size:23px;display:inline-block;\">\n\t<i class=\"linearicons-knife\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-3879 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Dramatically myocardinate generate functionalized channels unique methodologies.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; parallax_content=&#8221;off&#8221; fadeout_row=&#8221;fadeout_ro<br \/>\nw_value&#8221; seperator_enable=&#8221;off&#8221;][vc_column][vc_empty_space height=&#8221;80px&#8221;]<div class=\"ult-animation  ult-animate-viewport  ult-no-mobile \" data-animate=\"fadeIn\" data-animation-delay=\"0\" data-animation-duration=\"0.5\" data-animation-iteration=\"1\" style=\"opacity:0;\" data-opacity_start_effect=\"\"><div id=\"ultimate-heading-55616a987db38d3be\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-55616a987db38d3be uvc-5142 \" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-55616a987db38d3be h2'  data-responsive-json-new='{\"font-size\":\"desktop:18px;\",\"line-height\":\"\"}' ><h2 style=\"font-family:&#039;Courgette&#039;;font-weight:bold;color:__USE_THEME_MAIN_COLOR__;\">Web Font Icons<\/h2><\/div><div class=\"uvc-sub-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-55616a987db38d3be .uvc-sub-heading '  data-responsive-json-new='{\"font-size\":\"desktop:36px;\",\"line-height\":\"desktop:48px;\"}'  style=\"font-family:&#039;Montserrat&#039;;font-weight:700;color:#303030;margin-bottom:0px;\">RETINA ICONS<\/div><\/div>[vc_empty_space height=&#8221;10px&#8221;]<div id=\"ultimate-heading-85516a987db38d468\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-85516a987db38d468 uvc-4395 \" data-hspacer=\"line_with_icon\" data-hline_width=\"150\" data-hicon_type=\"selector\" data-hborder_style=\"solid\" data-hborder_height=\"1\" data-hborder_color=\"#e2e2e2\" data-icon_width=\"32\" data-hfixer=\"30\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer line_with_icon\" style=\"topheight:32px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#d87f93;font-size:32px;display:inline-block;\">\n\t<i class=\"linearicons-shield-check\"><\/i>\n<\/div><\/div><\/div><\/div><\/div>[vc_empty_space height=&#8221;60px&#8221;]<\/div>[\/vc_column][\/vc_row]\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1531501256718{padding-top: 80px !important;padding-bottom: 120px !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;INFO BOX | TOOLTIP DESCRIPTION&#8221; font_container=&#8221;tag:h2|font_size:18px|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_empty_space height=&#8221;80px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1462203830473{padding-top: 40px !important;padding-bottom: 40px !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;INFO BOX | CENTERED ICON&#8221; font_container=&#8221;tag:h2|font_size:18px|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_empty_space height=&#8221;80px&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1483479862325{padding-bottom: 50px !important;}&#8221;][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1462207384660{padding-bottom: 50px !important;}&#8221;][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row][vc_row bg_type=&#8221;bg_color&#8221; bg_override=&#8221;ex-full&#8221; css=&#8221;.vc_custom_1483481746588{padding-top: 120px !important;padding-bottom: 120px !important;}&#8221; bg_color_value=&#8221;#f7f7f7&#8243;][vc_column][vc_custom_heading text=&#8221;INFO BOX [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":2374,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page.php","meta":[],"_links":{"self":[{"href":"http:\/\/demos.upperthemes.com\/koral\/headerstyle3\/wp-json\/wp\/v2\/pages\/356"}],"collection":[{"href":"http:\/\/demos.upperthemes.com\/koral\/headerstyle3\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/demos.upperthemes.com\/koral\/headerstyle3\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/demos.upperthemes.com\/koral\/headerstyle3\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/demos.upperthemes.com\/koral\/headerstyle3\/wp-json\/wp\/v2\/comments?post=356"}],"version-history":[{"count":0,"href":"http:\/\/demos.upperthemes.com\/koral\/headerstyle3\/wp-json\/wp\/v2\/pages\/356\/revisions"}],"up":[{"embeddable":true,"href":"http:\/\/demos.upperthemes.com\/koral\/headerstyle3\/wp-json\/wp\/v2\/pages\/2374"}],"wp:attachment":[{"href":"http:\/\/demos.upperthemes.com\/koral\/headerstyle3\/wp-json\/wp\/v2\/media?parent=356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}